{"id":214,"count":2,"description":"","link":"https:\/\/www.comitatoperlinate.info\/index.php\/tag\/abbandono\/","name":"abbandono","slug":"abbandono","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.comitatoperlinate.info\/index.php\/wp-json\/wp\/v2\/tags\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comitatoperlinate.info\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.comitatoperlinate.info\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.comitatoperlinate.info\/index.php\/wp-json\/wp\/v2\/posts?tags=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}